{"id":17447,"date":"2026-05-13T10:05:56","date_gmt":"2026-05-13T07:05:56","guid":{"rendered":"https:\/\/live-kora-tv.com\/le-club-africain-met-en-vente-les-billets-pour-le-dernier-match-de-lolympi-al-baji\/"},"modified":"2026-05-13T10:05:59","modified_gmt":"2026-05-13T07:05:59","slug":"le-club-africain-met-en-vente-les-billets-pour-le-dernier-match-de-lolympi-al-baji","status":"publish","type":"post","link":"https:\/\/live-kora-tv.com\/fr\/le-club-africain-met-en-vente-les-billets-pour-le-dernier-match-de-lolympi-al-baji\/","title":{"rendered":"Le Club Africain met en vente les billets pour le dernier match de l&rsquo;Olympi Al Baji"},"content":{"rendered":"\n<p>Le club africain a annonc\u00e9 que les billets pour son match contre l&rsquo;Olympi Baji seront mis en vente mercredi, avant la rencontre, qui fait partie de la 30e et derni\u00e8re journ\u00e9e du championnat de Ligue 1. <\/p>\n\n<p>Le match aura lieu le jeudi 14 mai, \u00e0 partir de 16 heures, au stade Hammadi Larbi de Prades.  <\/p>\n\n<p>Le club a expliqu\u00e9 que la vente concernera les billets de l&rsquo;espace \u00ab\u00a0Soufflet\u00a0\u00bb, au prix de 30 dinars le billet, et sera disponible au guichet du stade Chadli Zouiten.  <\/p>\n\n<p>Ce match est particulier pour les supporters du club africain, puisqu&rsquo;il s&rsquo;agit du dernier match de la saison et qu&rsquo;il intervient apr\u00e8s que l&rsquo;\u00e9quipe a \u00e9t\u00e9 officiellement couronn\u00e9e championne.  <\/p>\n\n<p>Le match devrait attirer une foule nombreuse, les supporters de la nouvelle \u00e9quipe de Bab Al Jadid souhaitant f\u00eater le titre avec les joueurs, apr\u00e8s une saison qui s&rsquo;est achev\u00e9e par le retour du club sur le podium.  <\/p>\n\n<p>Les autorit\u00e9s charg\u00e9es de l&rsquo;organisation et de la s\u00e9curit\u00e9 devraient contr\u00f4ler la vente des billets et l&rsquo;entr\u00e9e des supporters dans le stade afin de s&rsquo;assurer que le match se d\u00e9roule sans encombre. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le club africain a annonc\u00e9 que les billets pour son match contre l&rsquo;Olympi Baji seront mis en vente mercredi, avant la rencontre, qui fait partie de la 30e et derni\u00e8re journ\u00e9e du championnat de Ligue 1. Le match aura lieu le jeudi 14 mai, \u00e0 partir de 16 heures, au stade Hammadi Larbi de Prades. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17445,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":{"0":"post-17447","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites-sportives"},"_links":{"self":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/17447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/comments?post=17447"}],"version-history":[{"count":1,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/17447\/revisions"}],"predecessor-version":[{"id":17448,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/17447\/revisions\/17448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media\/17445"}],"wp:attachment":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media?parent=17447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/categories?post=17447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/tags?post=17447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}