{"id":7707,"date":"2025-07-30T17:20:49","date_gmt":"2025-07-30T14:20:49","guid":{"rendered":"https:\/\/live-kora-tv.com\/greve-du-transport-routier-en-tunisie-luft-tient-le-ministere-des-finances-pour-responsable-et-affirme-sa-volonte-de-dialogue\/"},"modified":"2025-07-30T17:20:51","modified_gmt":"2025-07-30T14:20:51","slug":"greve-du-transport-routier-en-tunisie-luft-tient-le-ministere-des-finances-pour-responsable-et-affirme-sa-volonte-de-dialogue","status":"publish","type":"post","link":"https:\/\/live-kora-tv.com\/fr\/greve-du-transport-routier-en-tunisie-luft-tient-le-ministere-des-finances-pour-responsable-et-affirme-sa-volonte-de-dialogue\/","title":{"rendered":"Gr\u00e8ve du transport routier en Tunisie : L&rsquo;UFT tient le minist\u00e8re des Finances pour responsable et affirme sa volont\u00e9 de dialogue"},"content":{"rendered":"\n<p>A partir d&rsquo;aujourd&rsquo;hui, mercredi 30 juillet 2025, le secteur du transport routier en Tunisie conna\u00eet une <strong>gr\u00e8ve g\u00e9n\u00e9rale de trois jours<\/strong>, dans un contexte de blocage des n\u00e9gociations avec le minist\u00e8re du Transport sur un certain nombre de revendications syndicales. <\/p>\n\n<p><strong>Salaheddine Salmi<\/strong>, secr\u00e9taire g\u00e9n\u00e9ral adjoint de l&rsquo;UGTT, a exprim\u00e9 sur Mosa\u00efque FM la <strong>surprise du syndicat face au rejet par le minist\u00e8re des Finances de toutes les propositions<\/strong>, m\u00eame celles convenues lors de la premi\u00e8re session du dialogue.  <\/p>\n\n<p>Salmi a d\u00e9clar\u00e9 :<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Apr\u00e8s 11 heures de n\u00e9gociations, le dossier a \u00e9t\u00e9 transmis au minist\u00e8re des finances parce qu&rsquo;il y avait deux points qui avaient un impact financier, mais ils ont rejet\u00e9 toutes les propositions, m\u00eame les plus simples.   <\/p>\n<\/blockquote>\n\n<p>Il a soulign\u00e9 que <strong>c&rsquo;est<\/strong>le <strong>minist\u00e8re des Finances qui est responsable de l&rsquo;\u00e9chec des n\u00e9gociations<\/strong>, et non l&rsquo;UFT, ajoutant que le syndicat est <strong>pr\u00eat \u00e0 reprendre le dialogue<\/strong> et que \u00ab\u00a0les portes sont toujours ouvertes\u00a0\u00bb, comme il l&rsquo;a dit. <\/p>\n\n<p>Il a \u00e9galement expliqu\u00e9 que la <strong>gr\u00e8ve s&rsquo;inscrivait dans un cadre l\u00e9gal et constitutionnel<\/strong>, notant que le syndicat avait donn\u00e9 au minist\u00e8re des transports suffisamment de temps pour dialoguer, mais que le minist\u00e8re n&rsquo;avait organis\u00e9 aucune session de n\u00e9gociation pendant plus d&rsquo;un mois et demi, et s&rsquo;\u00e9tait content\u00e9 de publier une d\u00e9claration qualifiant les revendications d'\u00a0\u00bbinjustes\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir d&rsquo;aujourd&rsquo;hui, mercredi 30 juillet 2025, le secteur du transport routier en Tunisie conna\u00eet une gr\u00e8ve g\u00e9n\u00e9rale de trois jours, dans un contexte de blocage des n\u00e9gociations avec le minist\u00e8re du Transport sur un certain nombre de revendications syndicales. Salaheddine Salmi, secr\u00e9taire g\u00e9n\u00e9ral adjoint de l&rsquo;UGTT, a exprim\u00e9 sur Mosa\u00efque FM la surprise du [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-7707","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-communaute"},"_links":{"self":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/7707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/comments?post=7707"}],"version-history":[{"count":1,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/7707\/revisions"}],"predecessor-version":[{"id":7711,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/7707\/revisions\/7711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media\/7683"}],"wp:attachment":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media?parent=7707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/categories?post=7707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/tags?post=7707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}