{"id":9590,"date":"2025-09-15T17:47:53","date_gmt":"2025-09-15T14:47:53","guid":{"rendered":"https:\/\/live-kora-tv.com\/marco-rubio-arrive-a-doha-apres-une-visite-en-israel-et-un-sommet-arabo-islamique-durgence\/"},"modified":"2025-09-15T17:47:55","modified_gmt":"2025-09-15T14:47:55","slug":"marco-rubio-arrive-a-doha-apres-une-visite-en-israel-et-un-sommet-arabo-islamique-durgence","status":"publish","type":"post","link":"https:\/\/live-kora-tv.com\/fr\/marco-rubio-arrive-a-doha-apres-une-visite-en-israel-et-un-sommet-arabo-islamique-durgence\/","title":{"rendered":"Marco Rubio arrive \u00e0 Doha apr\u00e8s une visite en Isra\u00ebl et un sommet arabo-islamique d&rsquo;urgence"},"content":{"rendered":"\n<p>Le <strong>secr\u00e9taire d&rsquo;<\/strong> \u00c9tat am\u00e9ricain <strong>Marco Rubio<\/strong> se rendra \u00e0 <strong>Doha<\/strong> apr\u00e8s sa visite en Isra\u00ebl, a annonc\u00e9 lundi 15 septembre 2025 un haut responsable du d\u00e9partement d&rsquo;\u00c9tat, dans un contexte de tensions r\u00e9gionales r\u00e9sultant de la r\u00e9cente attaque isra\u00e9lienne contre des dirigeants du <strong>Hamas<\/strong> dans la capitale qatarie.   <\/p>\n\n<h4 class=\"wp-block-heading\"><strong>Contexte de la visite<\/strong><\/h4>\n\n<p>La visite de Rubio au Qatar intervient alors que Doha a accueilli un<strong>sommet arabo-islamique d&rsquo;urgence<\/strong>pour discuter des r\u00e9percussions de l&rsquo;attaque isra\u00e9lienne du mardi 9 septembre 2025, qui visait une d\u00e9l\u00e9gation de n\u00e9gociateurs du Hamas discutant d&rsquo;une proposition am\u00e9ricaine de cessez-le-feu \u00e0 <strong>Gaza<\/strong> pr\u00e9sent\u00e9e par le pr\u00e9sident <strong>Donald Trump<\/strong>, et qui a tu\u00e9 cinq membres du Hamas, dont le fils de Khalil al-Haya, le n\u00e9gociateur en chef du groupe, ainsi qu&rsquo;un agent de s\u00e9curit\u00e9 qatari. L&rsquo;attentat a tu\u00e9 cinq membres du Hamas, dont le fils de <strong>Khalil al-Haya<\/strong>, le n\u00e9gociateur en chef, ainsi qu&rsquo;un agent de s\u00e9curit\u00e9 qatari, mais n&rsquo;a pas vis\u00e9 les principaux dirigeants du mouvement.<\/p>\n\n<h4 class=\"wp-block-heading\"><strong>D\u00e9clarations de Rubio<\/strong><\/h4>\n\n<p>Lors de sa visite \u00e0 J\u00e9rusalem, M. Rubio a appel\u00e9 le Qatar \u00e0 poursuivre son r\u00f4le \u00ab\u00a0constructif\u00a0\u00bb dans les efforts de m\u00e9diation visant \u00e0 mettre fin \u00e0 la guerre \u00e0 Gaza, soulignant lors d&rsquo;une conf\u00e9rence de presse avec le Premier ministre isra\u00e9lien <strong>Benjamin Netanyahu<\/strong> que <strong>\u00ab\u00a0<\/strong>nous continuerons \u00e0 encourager le Qatar \u00e0 jouer un r\u00f4le constructif \u00e0 cet \u00e9gard\u00a0\u00bb : \u00ab\u00a0Nous continuerons \u00e0 encourager le Qatar \u00e0 jouer un r\u00f4le constructif \u00e0 cet \u00e9gard\u00a0\u00bb. Il a not\u00e9 que les \u00c9tats-Unis soutiennent la d\u00e9faite du Hamas, la fin de la guerre et le retour des otages, qui sont les priorit\u00e9s du pr\u00e9sident Trump.  <\/p>\n\n<h4 class=\"wp-block-heading\"><strong>La situation \u00e0 Gaza<\/strong><\/h4>\n\n<p>La visite de Rubio en Isra\u00ebl a co\u00efncid\u00e9 avec l&rsquo;escalade des op\u00e9rations militaires isra\u00e9liennes \u00e0 Gaza, les autorit\u00e9s palestiniennes confirmant la destruction d&rsquo;<strong>au moins 30 immeubles r\u00e9sidentiels<\/strong> dans la ville de Gaza et le d\u00e9placement de milliers de r\u00e9sidents. Selon le minist\u00e8re de la sant\u00e9 de Gaza, le nombre de morts depuis le d\u00e9but de la guerre, le 7 octobre 2023, s&rsquo;\u00e9l\u00e8ve \u00e0 <strong>64 871 martyrs<\/strong>, et <strong>90 %<\/strong> de la population de Gaza, qui compte environ deux millions d&rsquo;habitants, a \u00e9t\u00e9 d\u00e9plac\u00e9e.    <\/p>\n\n<h4 class=\"wp-block-heading\"><strong>R\u00e9actions r\u00e9gionales<\/strong><\/h4>\n\n<p>L&rsquo;attaque isra\u00e9lienne \u00e0 Doha a suscit\u00e9 une grande col\u00e8re dans le monde arabe. Le Qatar a d\u00e9nonc\u00e9 l&rsquo;attaque comme \u00e9tant du \u00ab\u00a0terrorisme sioniste\u00a0\u00bb, tandis que le Premier ministre qatari <strong>, Sheikh Mohammed bin Abdulrahman Al Thani<\/strong>, a appel\u00e9 la communaut\u00e9 internationale \u00e0 \u00ab\u00a0abandonner la politique du deux poids deux mesures\u00a0\u00bb et \u00e0 punir Isra\u00ebl pour ses \u00ab\u00a0crimes\u00a0\u00bb. Le Qatar a r\u00e9it\u00e9r\u00e9 son engagement \u00e0 jouer son r\u00f4le de m\u00e9diateur malgr\u00e9 l&rsquo;attaque, tandis que d&rsquo;autres pays arabes, comme les \u00c9mirats arabes unis, ont pr\u00e9venu que l&rsquo;escalade isra\u00e9lienne mena\u00e7ait les accords d&rsquo;<strong>Ibrahim<\/strong> en vue d&rsquo;une normalisation.      <\/p>\n\n<h4 class=\"wp-block-heading\"><strong>L&rsquo;importance de la visite<\/strong><\/h4>\n\n<p>La visite de M. Rubio au Qatar est une d\u00e9marche diplomatique d\u00e9licate visant \u00e0 r\u00e9tablir la confiance entre les \u00c9tats-Unis et leurs alli\u00e9s du Golfe, en particulier apr\u00e8s que la frappe isra\u00e9lienne a suscit\u00e9 des doutes quant \u00e0 la capacit\u00e9 de Washington \u00e0 prot\u00e9ger ses alli\u00e9s. \u00c0 Doha, M. Rubio devrait discuter de la poursuite de la m\u00e9diation qatarie, ainsi que d&rsquo;autres questions telles que la coop\u00e9ration en mati\u00e8re de d\u00e9fense entre les deux pays.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secr\u00e9taire d&rsquo; \u00c9tat am\u00e9ricain Marco Rubio se rendra \u00e0 Doha apr\u00e8s sa visite en Isra\u00ebl, a annonc\u00e9 lundi 15 septembre 2025 un haut responsable du d\u00e9partement d&rsquo;\u00c9tat, dans un contexte de tensions r\u00e9gionales r\u00e9sultant de la r\u00e9cente attaque isra\u00e9lienne contre des dirigeants du Hamas dans la capitale qatarie. Contexte de la visite La visite [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[],"class_list":{"0":"post-9590","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nouvelles-du-monde"},"_links":{"self":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/9590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/comments?post=9590"}],"version-history":[{"count":1,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/9590\/revisions"}],"predecessor-version":[{"id":9591,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/9590\/revisions\/9591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media\/9588"}],"wp:attachment":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media?parent=9590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/categories?post=9590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/tags?post=9590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}