{"id":9622,"date":"2025-09-16T13:06:49","date_gmt":"2025-09-16T10:06:49","guid":{"rendered":"https:\/\/live-kora-tv.com\/lor-atteint-un-niveau-record-en-raison-de-la-baisse-du-dollar-avant-les-decisions-de-la-fed\/"},"modified":"2025-09-16T13:06:50","modified_gmt":"2025-09-16T10:06:50","slug":"lor-atteint-un-niveau-record-en-raison-de-la-baisse-du-dollar-avant-les-decisions-de-la-fed","status":"publish","type":"post","link":"https:\/\/live-kora-tv.com\/fr\/lor-atteint-un-niveau-record-en-raison-de-la-baisse-du-dollar-avant-les-decisions-de-la-fed\/","title":{"rendered":"L&rsquo;or atteint un niveau record en raison de la baisse du dollar avant les d\u00e9cisions de la Fed"},"content":{"rendered":"\n<p>Le prix de l&rsquo;or a atteint son plus haut niveau historique le mardi 16 septembre 2025, soutenu par un dollar am\u00e9ricain plus faible \u00e0 l&rsquo;approche de la r\u00e9union de la R\u00e9serve f\u00e9d\u00e9rale (banque centrale am\u00e9ricaine) de cette semaine, dans un contexte de fortes attentes d&rsquo;une r\u00e9duction des taux d&rsquo;int\u00e9r\u00eat.  <\/p>\n\n<p>Sur le march\u00e9 au comptant, l&rsquo;or a gagn\u00e9 0,1 % \u00e0 3680,17 dollars l&rsquo;once, apr\u00e8s avoir atteint un sommet historique de 3689,27 dollars plus t\u00f4t dans la s\u00e9ance. Les contrats \u00e0 terme sur l&rsquo;or pour livraison en d\u00e9cembre se sont \u00e9tablis \u00e0 3718,80 dollars.  <\/p>\n\n<p>Quant aux autres m\u00e9taux pr\u00e9cieux :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Argent<\/strong>: Stabilisation sur le march\u00e9 au comptant \u00e0 42,71 dollars l&rsquo;once.<\/li>\n\n\n\n<li><strong>Platine<\/strong>: L\u00e9g\u00e8re baisse de 0,1 pour cent \u00e0 1399,40 dollars.<\/li>\n\n\n\n<li><strong>Palladium<\/strong>: En hausse de 0,4 % \u00e0 1188,59 $.<\/li>\n<\/ul>\n\n<p>Cette hausse intervient alors que les march\u00e9s attendent les d\u00e9cisions de politique mon\u00e9taire de la R\u00e9serve f\u00e9d\u00e9rale, car on pense qu&rsquo;une baisse des taux d&rsquo;int\u00e9r\u00eat pourrait renforcer l&rsquo;attrait de l&rsquo;or en tant que valeur refuge. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le prix de l&rsquo;or a atteint son plus haut niveau historique le mardi 16 septembre 2025, soutenu par un dollar am\u00e9ricain plus faible \u00e0 l&rsquo;approche de la r\u00e9union de la R\u00e9serve f\u00e9d\u00e9rale (banque centrale am\u00e9ricaine) de cette semaine, dans un contexte de fortes attentes d&rsquo;une r\u00e9duction des taux d&rsquo;int\u00e9r\u00eat. Sur le march\u00e9 au comptant, l&rsquo;or [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":{"0":"post-9622","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economie-et-affaires"},"_links":{"self":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/9622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/comments?post=9622"}],"version-history":[{"count":1,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/9622\/revisions"}],"predecessor-version":[{"id":9623,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/posts\/9622\/revisions\/9623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media\/9620"}],"wp:attachment":[{"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/media?parent=9622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/categories?post=9622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-kora-tv.com\/fr\/wp-json\/wp\/v2\/tags?post=9622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}